{"id":8842,"date":"2017-01-21T11:56:31","date_gmt":"2017-01-21T10:56:31","guid":{"rendered":"http:\/\/joachim-ortner.net\/viewju\/?p=8842"},"modified":"2021-01-18T14:06:56","modified_gmt":"2021-01-18T13:06:56","slug":"vietnam-mui-ne-wueste-wind-und-wellen","status":"publish","type":"post","link":"https:\/\/joachim-ortner.net\/viewju\/vietnam-mui-ne-wueste-wind-und-wellen\/","title":{"rendered":"Vietnam: Mui Ne &#8211; W\u00fcste, Wind und Wellen"},"content":{"rendered":"<p>14.1. &#8211; 20.1.2017<br \/>\nMui Ne \u2013 unser letzter Badeaufenthalt am Meer \u2013 hat keinen Flughafen in seiner N\u00e4he, sondern ist von Saigon aus in einer ca. 5-st\u00fcndigen Busfahrt erreichbar. Da es von Can Tho aus nicht m\u00f6glich war, verl\u00e4sslich einen Bus zu checken, gab\u00b4s f\u00fcr uns einen Zwischenstopp in Saigon.<\/p>\n<p>Tja: wir bemerkten sofort: auch beim 2. Besuch ist der Verkehr dort nicht weniger geworden&#8230;<\/p>\n<p>ngg_shortcode_0_placeholderZum Gl\u00fcck mussten wir nicht weit gehen, denn unser kleines Hotel war gleich in der N\u00e4he der Busstation und der Backpacker-Stra\u00dfe \u201eBui Vien\u201c. Dort findet man immer eine leckere Mahlzeit &#8211; der Wirbel auf der Stra\u00dfe bringt den Touristen jedoch in k\u00fcrzester Zeit an den Rand des Wahnsinns, welche nur noch durch ein oder zwei \u201eBia Saigon\u201c abgewehrt werden kann.<\/p>\n<p>ngg_shortcode_1_placeholderAm n\u00e4chsten Vormittag ging es im gem\u00fctlichen Liege-Bus (wenn man sich mal daran gew\u00f6hnt hat, sind die echt kommod) Richtung Strand &#8211; durch das Land der Drachenfruchtplantagen.<\/p>\n<p>ngg_shortcode_2_placeholderngg_shortcode_3_placeholderGenauer gesagt: f\u00fcr UNS kommod (also max. Gr\u00f6\u00dfe unter 1,75cm und max. Gewicht unter 80kg) &#8211; f\u00fcr andere Gr\u00f6\u00dfen schaut&#8217;s schlecht aus \ud83d\ude09<\/p>\n<p>ngg_shortcode_4_placeholderDamit wir uns schon ein bisserl an zu Hause gew\u00f6hnen k\u00f6nnen, haben wir uns f\u00fcr die Buchung eines Holz-Bungalows entschieden \ud83d\ude42<\/p>\n<p>ngg_shortcode_5_placeholderUnd nicht nur das Holzh\u00e4uschen erinnerte an daheim, das Coco-Palm Resort wird von einem deutsch\/franz\u00f6sischen Paar betrieben und vermittelt durchaus europ\u00e4isches Flair, allerdings inmitten vieler, vieler Palmen. Der Garten, die Sonnenschirme, die H\u00e4uschen \u2013 alles super gepflegt und akkurat und symmetrisch angeordnet. Am Strand immer genug Bettchen frei und wenn man das Bett umstellen wollte (z.B. in den Schatten) kam sofort einer der \u201eBeach-Boys\u201c und erledigt jeden Handgriff. Nicht mal das Handtuch durfte man selber ausbreiten. \ud83d\ude42 Was soll man sagen: faul sein mit Klasse!<\/p>\n<p>ngg_shortcode_6_placeholderUnd am Strand gibt es sogar ein sportliches Unterhaltungsprogramm: W\u00e4hrend man bequem am Liegebett knotzt, bieten die zahlreichen Kitesurfer eine Show aus bunte Segeln und tollen Spr\u00fcngen w\u00e4hrend sie \u00fcber das Wasser flitzen.<\/p>\n<p>ngg_shortcode_7_placeholderNach 4 Tagen intensiver Beobachtung des Surf-Verkehrs, beschlossen wir uns selbst mal einen Nachmittag lang dem Wind auszusetzen. Allerdings nicht auf dem Wasser sondern in einem uralten, fenster- und t\u00fcrenlosen Armee-Jeep, mit welchem wir eine Fahrt zur D\u00fcnenlandschaft von Mui Ne unternahmen.<\/p>\n<p>ngg_shortcode_8_placeholderGut gel\u00fcftet gab\u00b4s den ersten Halt bei einer Sehensw\u00fcrdigkeit namens \u201eFairy Stream\u201c. Vor lauter \u201efaul sein mit Klasse\u201c hatten wir uns allerdings nicht so gut vorbereitet, denn der \u201eFairy Stream\u201c entpuppte sich als \u2013 kn\u00f6chel- bis wadentiefer Bach \u2013 durch welchen der interessierte Tourist eine Viertelstunde durchwaten kann um an den Ufern die Felsformationen zu bestaunen. Da wir leider keine Trekking-Sandalen an bzw. beim Ausflug mithatten, fiel dieser Programmpunkt umgehend aus. Der Bach \u2013 eine braune, undurchsichtige Pl\u00f6rre \u2013 kann (insbesondere aus Uschis Sicht) keinesfalls ohne Schuhe betreten werden (wer wei\u00df was da drin ist..) Joachim, stets auf der Jagd nach dem perfekten Foto, w\u00e4re ja eventuell dazu bereit gewesen \u2013 aber wie hei\u00dft es so sch\u00f6n \u201eSicherheit geht vor \ud83d\ude09 \u201c.<\/p>\n<p>\u201eFairy Stream\u201c war jedoch bestimmt kein gro\u00dfer Verlust, denn der Tag bot zahlreiche wundersch\u00f6ne Fotomotive:<\/p>\n<p>Der Fischerhafen von Mui Ne (leider vom vollkommen fehlenden Umweltbewusstsein in seiner grunds\u00e4tzlichen Sch\u00f6nheit vollkommen zugem\u00fcllt):<\/p>\n<p>ngg_shortcode_9_placeholderDie Landschaft der \u201ewei\u00dfen D\u00fcnen\u201c, samt fotografierenden asiatischen Touristinnen und herumd\u00fcsenden Quads. Leider konnten wir uns kein Quad mieten, da wir nicht genug Geld dabei hatten (eh scho wissen \u2013 nicht ausreichend vorbereitet&nbsp;&#8211; weil faul\u2026). Deshalb waren wir nun gar nicht faul und haben die D\u00fcnen zu Fu\u00df erklommen. War lang nicht so schlimm wie die vielen Stufen in Angkor&#8230;)<\/p>\n<p>ngg_shortcode_10_placeholderN\u00e4chster Stop war der \u201eRed Canion\u201c \u2013 ein Graben aus extrem rotem Sand, quasi mitten in der Landschaft:<\/p>\n<p>ngg_shortcode_11_placeholderZum Abschluss gab\u00b4s noch einen Sonnenuntergang bei den \u201eroten D\u00fcnen\u201c&nbsp; &#8211; sandig, windig, sch\u00f6n.<\/p>\n<p>ngg_shortcode_12_placeholderNach den gem\u00fctlichen, faulen Tagen waren wir wieder bereit f\u00fcr Saigon. Da wir ja mit dem Bus wieder zur\u00fcck mussten und der vietnamesische Verkehr weder \u00fcber Land noch in der Stadt einsch\u00e4tzbar ist, trauten wir uns nicht die Fahrt mit dem Bus nach Saigon und den Flug nach Bangkok am gleichen Tag zu planen. Also: Saigon die Dritte \ud83d\ude42<\/p>\n<p>Jetzt kenn ma uns ja wirklich schon aus in der Stadt des Ho-Chi-Min :-), schl\u00e4ngeln uns furchtlos durch die Mopeds, husten auch nicht mehr ganz so viel, und bloggen brav im Hotel.<\/p>\n<p>ngg_shortcode_13_placeholderAber die Bui Vien ist nach wie vor ohne ausreichend \u201eBia Saigon\u201c nicht bew\u00e4ltigbar. Und die gab&#8217;s dann auch, ein bisserl wehm\u00fctig zum letzten Mal, stilecht auf kleinen Plastiksesserln, bevor es zur letzten Station, nach Bangkok, weiterging.<\/p>\n<p>ngg_shortcode_14_placeholderDort m\u00fcssen wir allerdings nochmal unsere Kr\u00e4fte b\u00fcndeln, denn: wir haben vom Aufenthalt im Dezember in Krabi noch einige Baht \u00fcber und der \u201eWeekend-Market\u201c wartet schon auf uns!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>14.1. &#8211; 20.1.2017 Mui Ne \u2013 unser letzter Badeaufenthalt am Meer \u2013 hat keinen Flughafen in seiner N\u00e4he, sondern ist von Saigon aus in einer ca. 5-st\u00fcndigen Busfahrt&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8886,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10,15,17,9],"tags":[],"class_list":["post-8842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asien","category-reiseblogs","category-suedostasien1617","category-vergangenes"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6X4XM-2iC","jetpack-related-posts":[{"id":6953,"url":"https:\/\/joachim-ortner.net\/viewju\/vietnam-ho-chi-minh-city-saigon\/","url_meta":{"origin":8842,"position":0},"title":"Vietnam: Ho Chi Minh City (Saigon)","author":"Joachim","date":"5. Dezember 2016","format":false,"excerpt":"1.12.- 5.12. Nach Hanoi dachten wir, dass das Verkehrschaos keine Steigerung mehr zul\u00e4sst, doch in Saigon hat das Chaos bereits bei der Anreise begonnen. Die Fahrt vom Hotel in Hue zum \u00f6rtlichen Flughafen funktionierte mit einem der netten Fahrer vom Stop 'n Go Cafe perfekt und p\u00fcnktlich. Aber als wir\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161204-IMG_1268.jpg?fit=960%2C640&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161204-IMG_1268.jpg?fit=960%2C640&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161204-IMG_1268.jpg?fit=960%2C640&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161204-IMG_1268.jpg?fit=960%2C640&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8818,"url":"https:\/\/joachim-ortner.net\/viewju\/vietnam-can-tho-im-mekong-delta-genuss-fuer-alle-sinne\/","url_meta":{"origin":8842,"position":1},"title":"Vietnam: Can Tho im Mekong-Delta &#8211; Genuss f\u00fcr alle Sinne","author":"Joachim","date":"15. Januar 2017","format":false,"excerpt":"9.1.2017 - 14.1.2017 Von der Insel Phu Quoc ging's weiter ins Mekong-Delta vor allem, um einen der schwimmenden Gro\u00df-M\u00e4rkte zu besuchen. Wir entschieden uns f\u00fcr einen Aufenthalt im Universit\u00e4ts-St\u00e4dtchen Can Tho (trotz 250.000 Einwohnern ein St\u00e4dtchen, da es mehr ein zusammengewachsenes Gebiet lose verbundener Siedlungen ist), welches in unmittelbarer N\u00e4he\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20170112-IMG_3059.jpg?fit=960%2C640&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20170112-IMG_3059.jpg?fit=960%2C640&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20170112-IMG_3059.jpg?fit=960%2C640&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20170112-IMG_3059.jpg?fit=960%2C640&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6957,"url":"https:\/\/joachim-ortner.net\/viewju\/back-to-thailand-khao-lak-phuket-old-town-krabi\/","url_meta":{"origin":8842,"position":2},"title":"Back to Thailand: Khao Lak &#8211; Phuket Old Town &#8211; Krabi","author":"Joachim","date":"24. Dezember 2016","format":false,"excerpt":"12.12. - 24.12. Wir wollen Meer! Nachdem wir inzwischen 9 St\u00e4dte in 4 L\u00e4ndern besichtigt, 2 Mini-Kreuzfahrten absolviert und unz\u00e4hlige Tempel in Angkor erklommen haben, wollen wir nur noch eines: Absolute Ruhe und m\u00f6glichst\u00a0NICHTS \u00a0selber organisieren ... Was liegt da n\u00e4her als ein 7-Tage-Paket-Angebot eines Strandhotels zu nutzen. 7 Tage\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/12\/wp-1482497238691.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/12\/wp-1482497238691.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/12\/wp-1482497238691.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/12\/wp-1482497238691.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/12\/wp-1482497238691.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6959,"url":"https:\/\/joachim-ortner.net\/viewju\/malaysia-merry-christmas-kuala-lumpur\/","url_meta":{"origin":8842,"position":3},"title":"Malaysia: Merry Christmas Kuala Lumpur","author":"Joachim","date":"29. Dezember 2016","format":false,"excerpt":"24.12. - 28.12.2016 Was uns in Kuala Lumpur am besten gefallen hat ? Platz 1: Unser Zimmer im Hotel Majestic Platz 2: Der Afternoon-Tea im Hotel Majestic Platz 3: Das Fr\u00fchst\u00fcck im Hotel Majestic Und zur Erinnerung an die Leser, die auch schauen wollen: wenn man Fotos anklickt, bekommt man\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161226-20161226_214718.jpg?fit=960%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161226-20161226_214718.jpg?fit=960%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161226-20161226_214718.jpg?fit=960%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161226-20161226_214718.jpg?fit=960%2C540&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3915,"url":"https:\/\/joachim-ortner.net\/viewju\/ko-phayam-2\/","url_meta":{"origin":8842,"position":4},"title":"Thailand 2016 &#8211; Ko Phayam 2","author":"Joachim","date":"21. Januar 2016","format":false,"excerpt":"23.1. Da man ja nicht nur faul herum liegen kann, \u00a0ein Tag Insel erkunden ist ja kein Aufwand. Womit? Zuerst mal zum Pier mit dem Motorrad Taxi. (Nordost) \u00a0 Ein Kaffee zur St\u00e4rkung nach den ersten Anstrengungen ist unbedingt notwendig. Neue Freundschaften wurden geschlossen Da ich kein Motorrad aus leihen\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/01\/wp-1453376985937.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/01\/wp-1453376985937.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/01\/wp-1453376985937.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/01\/wp-1453376985937.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/2016\/01\/wp-1453376985937.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6961,"url":"https:\/\/joachim-ortner.net\/viewju\/malaysia-georgetown-strassenkunst-und-kueche\/","url_meta":{"origin":8842,"position":5},"title":"Malaysia: Georgetown &#8211; Stra\u00dfenkunst und K\u00fcche","author":"Joachim","date":"3. Januar 2017","format":false,"excerpt":"28.12.2016 - 2.1.2017 Die Insel Penang mit ihrer Hauptstadt Georgetown\u00a0wird im Reisef\u00fchrer und in diversen Foren als hippes, s\u00fcdostasiatisches Multikultizentrum, mit Stra\u00dfenkunst- und K\u00fcche sowie einer Weltkulturerbe-Altstadt angepriesen. Das klang verlockend, um dort einige Tage und gleich auch Silvester zu verbringen - in so einer vielf\u00e4ltigen Stadt sollte doch einiges\u2026","rel":"","context":"In &quot;Asien&quot;","block_context":{"text":"Asien","link":"https:\/\/joachim-ortner.net\/viewju\/category\/vergangenes\/asien\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161231-IMG_2633.jpg?fit=960%2C640&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161231-IMG_2633.jpg?fit=960%2C640&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161231-IMG_2633.jpg?fit=960%2C640&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20161231-IMG_2633.jpg?fit=960%2C640&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/joachim-ortner.net\/viewju\/wp-content\/uploads\/ngg_featured\/20170118-IMG_3158.jpg?fit=960%2C640&ssl=1","_links":{"self":[{"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/posts\/8842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/comments?post=8842"}],"version-history":[{"count":2,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/posts\/8842\/revisions"}],"predecessor-version":[{"id":9890,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/posts\/8842\/revisions\/9890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/media\/8886"}],"wp:attachment":[{"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/media?parent=8842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/categories?post=8842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/joachim-ortner.net\/viewju\/wp-json\/wp\/v2\/tags?post=8842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}